{"id":1181,"date":"2018-11-29T08:07:00","date_gmt":"2018-11-29T13:07:00","guid":{"rendered":"https:\/\/www.leryca.com\/product\/rose-gold-plated-family-tree-necklace-with-birthstones\/"},"modified":"2020-05-19T04:30:47","modified_gmt":"2020-05-19T08:30:47","slug":"rose-gold-plated-family-tree-necklace-with-birthstones","status":"publish","type":"product","link":"https:\/\/momgot.com\/it\/product\/rose-gold-plated-family-tree-necklace-with-birthstones\/","title":{"rendered":"Collana albero genealogico placcato oro rosa con pietre di nascita"},"content":{"rendered":"<p>Ti piace l&#039;aspetto delle collane dell&#039;albero genealogico? Questo ti consente di mostrare con gusto la tua connessione con le persone che ami di pi\u00f9. Nostro\u00a0<b>Collana albero genealogico placcato oro con pietre preziose<\/b>\u00a0fa un regalo bellissimo e significativo per tutte le occasioni, specialmente quando lo dai a mamma o nonna.<\/p>\n<p>Scegli fino a sei nomi e pietre preziose corrispondenti da aggiungere a questo sofisticato ciondolo, che \u00e8 graziosamente sospeso da a\u00a0<b>catena Rollo placcata oro<\/b>\u00a0per un look perfettamente coordinato. Questa collana dell&#039;albero genealogico \u00e8 disponibile anche in argento; qualunque cosa tu preferisca, apprezzerai il modo in cui ti ricorda i tuoi cari mentre aggiungi un tocco di brillantezza a tutti i tuoi outfit preferiti.<\/p>","protected":false},"excerpt":{"rendered":"<p>Love the look of\u00a0family tree necklaces? This one lets you tastefully display your connection to the ones you love most. Our\u00a0Gold Plated Family Tree Necklace with Birthstones\u00a0makes a beautiful and meaningful all-occasion gift, especially when you give it to mom or grandma. Choose up to six names and corresponding birthstones to add to this sophisticated [&#8230;]\n","protected":false},"featured_media":1182,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[83,95,78],"product_tag":[],"class_list":["post-1181","product","type-product","status-publish","has-post-thumbnail","product_cat-18k-rose-gold","product_cat-gifts-for-grandmother","product_cat-moms-necklaces","tm-has-options","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/product\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/comments?post=1181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/media\/1182"}],"wp:attachment":[{"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/product_brand?post=1181"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/product_cat?post=1181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/momgot.com\/it\/wp-json\/wp\/v2\/product_tag?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}